{"id":30065,"date":"2024-01-26T16:15:55","date_gmt":"2024-01-26T16:15:55","guid":{"rendered":"https:\/\/visualjournalism.de\/?post_type=magazin&#038;p=30065"},"modified":"2026-03-03T11:16:42","modified_gmt":"2026-03-03T09:16:42","slug":"einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel","status":"publish","type":"magazin","link":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/","title":{"rendered":"Einkaufen mit Autismus: Zu hell, zu laut, zu viel"},"content":{"rendered":"\r\n<div class=\"cover--lead-in has-spacing--m\">\r\n\r\n    \r\n    <div class=\"cover--lead-in__content typo--tiempos\">\r\n\r\n        <div class=\"entry-categories\">\n\t<a class=\"post__tag\" href=\"https:\/\/visualjournalism.de\/magazin-kategorie\/stille\/\" rel=\"category tag\">Stille<\/a><\/div>\r\n        <h2 class=\"cover--lead-in__headline headline-size--default\">\r\n            Zu hell, zu laut, zu viel        <\/h2>\r\n\r\n                    <div class=\"cover--lead-in__text\">\r\n                <p>F\u00fcr <a href=\"https:\/\/visualjournalism.de\/en\/marlene-fliege\/\"><strong>Marlene Fliege<\/strong><\/a> ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin. Was es f\u00fcr sie bedeutet, wenn ihre Lieblingsschokolade ausverkauft ist, und wie sie mit der Belastung umgeht.<\/p>\n            <\/div>\r\n        \r\n                    <div class=\"cover--lead-in__author\">\r\n                \r\n                    \r\n                            <figure class=\"cover--lead-in__author__image\">\r\n\r\n                                                                    <a href=\"https:\/\/visualjournalism.de\/marlene-fliege\/(\u00f6ffnet%20in%20neuem%20Tab)\" target=\"\">\r\n                                \r\n                                <img loading=\"lazy\" decoding=\"async\"\r\n                                    src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/RL-STILLE-Exporter-V02-1-2-68x68.jpg\"\r\n                                    srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/RL-STILLE-Exporter-V02-1-2-68x68.jpg 68w, https:\/\/visualjournalism.de\/wp-content\/uploads\/RL-STILLE-Exporter-V02-1-2-52x52.jpg 52w, https:\/\/visualjournalism.de\/wp-content\/uploads\/RL-STILLE-Exporter-V02-1-2-96x96.jpg 96w, https:\/\/visualjournalism.de\/wp-content\/uploads\/RL-STILLE-Exporter-V02-1-2.jpg 100w\"\r\n                                    width=\"68\"\r\n                                    height=\"68\"\r\n                                    alt=\"\"\r\n                                \/>\r\n\r\n                                                                    <\/a>\r\n                                \r\n                            <\/figure>\r\n\r\n                        \r\n                                <\/div><!-- .cover--lead-in__author -->\r\n        \r\n    <\/div><!-- .cover--lead-in__content -->\r\n\r\n    \r\n        <figure class=\"cover--lead-in__image cover--lead-in__media cover--lead-in__media--image\">\r\n            <img loading=\"lazy\" decoding=\"async\"\r\n                src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1920x1280.jpg\"\r\n                srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1920x1280.jpg 1920w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-300x200.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1024x682.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-768x512.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1536x1024.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1400x933.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-1050x700.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-670x447.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-420x280.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-350x233.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille-150x100.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg 2000w\"\r\n                width=\"1920\"\r\n                height=\"1280\"\r\n                alt=\"Eine Frau kauft im Edeka am Herrenh\u00e4user Markt in Hannover bei ged\u00e4mmten Licht ein\"\r\n                style=\"object-position: 25% 56.5%\"\r\n            \/>\r\n        <\/figure>\r\n\r\n                    <span class=\"cover--lead-in__image-title\">\r\n                Hannover, Herrenhausen.\r\rDer Edeka am Herrenh\u00e4user Markt 3 erm\u00f6glicht mit der \u201eStillen Stunde\u201c ein reizreduziertes Einkaufen. Die Lichter werden gedimmt und Ger\u00e4usche wie Kassen und Musik reduziert.\u00a0\u00a0\r\r(Foto: Jonas Dengler)            <\/span>\r\n        \r\n    \r\n<\/div><!-- .cover--lead-in -->\r\n\r\n\n\n\n<p class=\"post__paragraph has-spacing--m\"><strong>Mit einem klaren Ziel vor Augen mache ich mich auf,<\/strong> in die Welt von Gem\u00fcsekonserven und Werbebannern \u2013 die Supermarkt-H\u00f6lle. Das dort angebotene Spektrum fast so vielf\u00e4ltig, wie das meiner Krankheit: Autismus. Irgendwo zwischen der Hafermilch und der Tiefk\u00fchlabteilung lauert bereits der n\u00e4chste Nervenzusammenbruch. Ich schlie\u00dfe die Augen, atme ein paar Mal tief ein und aus und visualisiere die Dinge, die ich brauche. \u00abSchei\u00dfe!\u00bb, entf\u00e4hrt es mir: Meine Lieblingsschokolade ist heute ausverkauft!<br><br>An gewohnter Stelle t\u00fcrmt sich eine Bandbreite anderer Tafeln vor mir auf \u2013 so angsteinfl\u00f6\u00dfend und schier endlos wie der Weg nach Mordor. Jede einzelne muss ich nun genau unter die Lupe nehmen, Vor- und Nachteile w\u00e4ge ich sorgf\u00e4ltig ab, bis ich \u00fcberhaupt nur daran denken kann, eine von ihnen in den Einkaufskorb zu packen. W\u00e4hrend meiner unabdingbaren Analyse bahnen sich stechende Kopfschmerzen an. Die Supermarktlichter wirken auf mich wie auf einer Techno-Party. Zeternde Mitmenschen und schreiende Kinder kann ich sogar durch meine ger\u00e4uschabweisenden Kopfh\u00f6rer nicht ausblenden. Frustriert gebe ich meine Inspektion auf und entscheide, einfach so lange andere Superm\u00e4rkte abzuklappern, bis ich meine Lieblingstafel bekomme. <\/p>\n\n\n\n \n    \n    <div id=\"quote-block_2e0423860f5f956e3e3ce47ab73ac638\" class=\"block-quote has-spacing--m\">\n        <figure class=\"quote\">\n            <blockquote>\n                <p><strong>Irgendwo zwischen der Hafermilch<\/strong> und der Tiefk\u00fchlabteilung lauert bereits der n\u00e4chste Nervenzusammenbruch.<\/p>\n            <\/blockquote>\n\n            <figcaption>\n\n                            <span><\/span>\n            <\/figcaption>\n            \n        <\/figure>\n    <\/div>\n\n\n\n\n<p class=\"post__paragraph has-spacing--default\"><strong>Auch wenn sich mir bei dieser Aussicht der Magen umdreht<\/strong>, ist das doch besser, als noch eine Sekunde l\u00e4nger an Ort und Stelle zu bleiben. Also rein in den n\u00e4chsten Markt, Ziel anvisieren, einpacken, bezahlen und so schnell, wie mich meine Beine tragen k\u00f6nnen, wieder aus dem Laden hinausst\u00fcrmen. Ersch\u00f6pft sinke ich in den Autositz und mache ein paar Atem\u00fcbungen. Die Hitze nagt an mir, pl\u00f6tzlich habe ich das Gef\u00fchl, dass jede Empfindung zu viel ist. Ich sp\u00fcre den Stoff meiner Klamotten wie Schleifpapier auf meiner Haut, meinen eigenen Atem wie S\u00e4ure in meiner Lunge und zu allem \u00dcberfluss bin ich mir der Existenz meiner Zehen gerade viel zu bewusst.<\/p>\n\n\n\n<p class=\"post__paragraph has-spacing--m\">Das kurze Abenteuer hat mich so au\u00dfer Gefecht gesetzt, dass ich f\u00fcr den Rest des Tages, nur noch zum Pipimachen mein Bett verlassen kann. Das Rollo ist runtergezogen, alle T\u00fcren sind zu und die wohlige Stille beruhigt meinen Geist. Gott sei Dank habe ich liebevolle Menschen um mich herum, die mich auffangen k\u00f6nnen, wenn mein K\u00f6rper und Verstand aufgrund von sensorischer \u00dcberbelastung mal wieder streiken. <br><br>Doch nicht jeder Mensch aus dem Autismus-Spektrum hat dieses Privileg. Wenn euch die Menschen um euch herum wieder einmal komisch erscheinen oder gar unwirsch und unh\u00f6flich, bitte bedenkt: Vielleicht seid ihr nur mal wieder einer neurodivergenten Person begegnet, auf ihrer verzweifelten Suche nach Stille.<\/p>\n\n\n\n<div class=\"wp-block-group has-color-14-background-color has-background has-spacing--default\">\n \n\n    <div id=\"accordion-block_0b6d81dc247ebc2ca00ee5890195dd09\" class=\"accordion has-spacing--s initial--open\">\n        <div class=\"accordion__title is-open\">\n            <h5>Was ist Autismus?<\/h5>\n            <span><\/span>\n        <\/div>\n\n        <div class=\"accordion__text\">\n         <p>Autismus ist eine neurologische Entwicklungsst\u00f6rung, die die Art und Weise beeinflusst, wie Menschen Informationen wahrnehmen, soziale Interaktionen erleben und kommunizieren. Es existiert ein breites Spektrum von Verhaltensweisen und Merkmalen, die alle autistisch genannt werden, weshalb man oft von Autismus-Spektrum-St\u00f6rungen (ASS) spricht.<\/p>\n        <\/div>\n    <\/div>\n\n\n\n\n \n\n    <div id=\"accordion-block_7ecef5d7537c168df2829041bbb187c0\" class=\"accordion has-spacing--s\">\n        <div class=\"accordion__title\">\n            <h5>Wie macht sich Autismus bemerkbar?<\/h5>\n            <span><\/span>\n        <\/div>\n\n        <div class=\"accordion__text\">\n         <p>Die Art und Weise, wie sich Autismus \u00e4u\u00dfert, variiert von Person zu Person. Einige gemeinsame Merkmale sind Schwierigkeiten in der sozialen Interaktion, eingeschr\u00e4nkte Kommunikation, repetitive Verhaltensweisen und Interessen sowie sensorische Empfindlichkeiten. Manche Menschen mit Autismus haben besondere F\u00e4higkeiten oder Interessen in bestimmten Bereichen.<\/p>\n        <\/div>\n    <\/div>\n\n\n\n\n \n\n    <div id=\"accordion-block_f5f77581213dd6c92d2ca1ea2cca5e50\" class=\"accordion has-spacing--s\">\n        <div class=\"accordion__title\">\n            <h5>Was ist das Asperger-Syndrom?<\/h5>\n            <span><\/span>\n        <\/div>\n\n        <div class=\"accordion__text\">\n         <p>Das Asperger-Syndrom ist eine Form des Autismus-Spektrums, die sich durch normale bis \u00fcberdurchschnittliche Intelligenz, besondere Interessen, Schwierigkeiten in der sozialen Interaktion und eingeschr\u00e4nkte Kommunikation auszeichnet. Im Vergleich zu anderen Autismus-Formen haben Menschen mit Asperger-Syndrom oft keine Beeintr\u00e4chtigung in der Sprachentwicklung, was ihnen erm\u00f6glicht, spezielle Talente zu entwickeln.<\/p>\n<p>Der Begriff\u00a0 &#8220;Asperger-Syndrom&#8221; wurde im durch den allgemeineren Begriff &#8220;Autismus-Spektrum-St\u00f6rungen&#8221; ersetzt, um die Vielfalt des Autismus-Spektrums zu betonen.<\/p>\n        <\/div>\n    <\/div>\n\n\n\n\n \n\n    <div id=\"accordion-block_aab83e9176b3d870b22e2bd1797fa1c6\" class=\"accordion has-spacing--s\">\n        <div class=\"accordion__title\">\n            <h5>Anmerkungen der Autorin<\/h5>\n            <span><\/span>\n        <\/div>\n\n        <div class=\"accordion__text\">\n         <p>Wenn ihr euch weiter \u00fcber das Gesamtbild Asperger\/Autismus\/Neurodivergenz informieren wollt, kann ich<br \/>\ndies nur empfehlen. Gerade die Unterschiede zwischen cis-m\u00e4nnlichen Personen und allen anderen Geschlechtsorientierungen sind enorm, da die medizinischen Erkenntnisse sich haupts\u00e4chlich auf den Stereotyp \u201eMann\u201c beziehen. Eine spannende Lekt\u00fcre ist zum Beispiel \u201eAspergirls\u201c von Rudy Simone. Empfehlenswert ist auch das Video auf dem Youtube-Channel \u201eauf Klo\u201c mit dem Titel \u201eAutismus: ich habe das Asperger-Syndrom\u201c, um ein paar Klischees aus dem Weg zu r\u00e4umen. Eine vorurteilsfreie Art an Betroffene heranzugehen, ist immer die Beste \u2013 fernab von medialen Darstellungen und \u00f6ffentlichen oder auch eigenen Stigmata.<\/p>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n","protected":false},"author":54,"featured_media":30896,"template":"","tags":[],"magazinkategorie":[170],"class_list":["post-30065","magazin","type-magazin","status-publish","has-post-thumbnail","hentry","magazinkategorie-stille"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Einkaufen mit Autismus: Zu hell, zu viel, zu laut<\/title>\n<meta name=\"description\" content=\"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einkaufen mit Autismus: Zu hell, zu laut, zu viel\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/\" \/>\n<meta property=\"og:site_name\" content=\"Visual Journalism and Documentary Photography\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T09:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HsHannover\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/\",\"name\":\"Einkaufen mit Autismus: Zu hell, zu viel, zu laut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Jonas_Dengler-Einkaufen-in-Stille.jpg\",\"datePublished\":\"2024-01-26T16:15:55+00:00\",\"dateModified\":\"2026-03-03T09:16:42+00:00\",\"description\":\"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Jonas_Dengler-Einkaufen-in-Stille.jpg\",\"contentUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Jonas_Dengler-Einkaufen-in-Stille.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Hannover, Herrenhausen. Der Edeka am Herrenh\u00e4user Markt 3 erm\u00f6glicht mit der \u201eStillen Stunde\u201c ein reizreduziertes Einkaufen. Die Lichter werden gedimmt und Ger\u00e4usche wie Kassen und Musik reduziert.\u00a0\u00a0 (Foto: Jonas Dengler)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/stille\\\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazin\",\"item\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Einkaufen mit Autismus: Zu hell, zu laut, zu viel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\",\"name\":\"Visual Journalism and Documentary Photography\",\"description\":\"All about the bilingual bachelor&#039;s program at Hannover University of Applied Sciences and Arts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#organization\"},\"alternateName\":\"visualjournalism.de\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#organization\",\"name\":\"Hochschule Hannover \u2013 University of Applied Sciences and Arts\",\"alternateName\":\"HsH\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/logo-hochschule-hannover.png\",\"contentUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/logo-hochschule-hannover.png\",\"width\":363,\"height\":270,\"caption\":\"Hochschule Hannover \u2013 University of Applied Sciences and Arts\"},\"image\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/wwwfotostudentende\\\/100065173703897\\\/\",\"https:\\\/\\\/x.com\\\/HsHannover\",\"https:\\\/\\\/www.instagram.com\\\/visualjournalism.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Einkaufen mit Autismus: Zu hell, zu viel, zu laut","description":"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/","og_locale":"en_US","og_type":"article","og_title":"Einkaufen mit Autismus: Zu hell, zu laut, zu viel","og_description":"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.","og_url":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/","og_site_name":"Visual Journalism and Documentary Photography","article_publisher":"https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/","article_modified_time":"2026-03-03T09:16:42+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@HsHannover","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/","url":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/","name":"Einkaufen mit Autismus: Zu hell, zu viel, zu laut","isPartOf":{"@id":"https:\/\/visualjournalism.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/#primaryimage"},"image":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/#primaryimage"},"thumbnailUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg","datePublished":"2024-01-26T16:15:55+00:00","dateModified":"2026-03-03T09:16:42+00:00","description":"F\u00fcr unsere Autorin ist der Gang zum Supermarkt die H\u00f6lle. Lampen, Werbung und Ger\u00e4usche \u00fcberfordern die junge Autistin.","breadcrumb":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/#primaryimage","url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg","contentUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Jonas_Dengler-Einkaufen-in-Stille.jpg","width":2000,"height":1333,"caption":"Hannover, Herrenhausen. Der Edeka am Herrenh\u00e4user Markt 3 erm\u00f6glicht mit der \u201eStillen Stunde\u201c ein reizreduziertes Einkaufen. Die Lichter werden gedimmt und Ger\u00e4usche wie Kassen und Musik reduziert.\u00a0\u00a0 (Foto: Jonas Dengler)"},{"@type":"BreadcrumbList","@id":"https:\/\/visualjournalism.de\/en\/magazine\/stille\/einkaufen-mit-autismus-zu-hell-zu-laut-zu-viel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visualjournalism.de\/en\/"},{"@type":"ListItem","position":2,"name":"Magazin","item":"https:\/\/visualjournalism.de\/en\/magazine\/"},{"@type":"ListItem","position":3,"name":"Einkaufen mit Autismus: Zu hell, zu laut, zu viel"}]},{"@type":"WebSite","@id":"https:\/\/visualjournalism.de\/en\/#website","url":"https:\/\/visualjournalism.de\/en\/","name":"Visual Journalism and Documentary Photography","description":"All about the bilingual bachelor&#039;s program at Hannover University of Applied Sciences and Arts.","publisher":{"@id":"https:\/\/visualjournalism.de\/en\/#organization"},"alternateName":"visualjournalism.de","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visualjournalism.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visualjournalism.de\/en\/#organization","name":"Hochschule Hannover \u2013 University of Applied Sciences and Arts","alternateName":"HsH","url":"https:\/\/visualjournalism.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visualjournalism.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/logo-hochschule-hannover.png","contentUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/logo-hochschule-hannover.png","width":363,"height":270,"caption":"Hochschule Hannover \u2013 University of Applied Sciences and Arts"},"image":{"@id":"https:\/\/visualjournalism.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/","https:\/\/x.com\/HsHannover","https:\/\/www.instagram.com\/visualjournalism.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin\/30065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin"}],"about":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/types\/magazin"}],"author":[{"embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/users\/54"}],"version-history":[{"count":1,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin\/30065\/revisions"}],"predecessor-version":[{"id":69567,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin\/30065\/revisions\/69567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/media\/30896"}],"wp:attachment":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/media?parent=30065"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/tags?post=30065"},{"taxonomy":"magazinkategorie","embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazinkategorie?post=30065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}