{"id":40823,"date":"2024-07-19T11:51:54","date_gmt":"2024-07-19T11:51:54","guid":{"rendered":"https:\/\/visualjournalism.de\/?post_type=magazin&#038;p=40823"},"modified":"2024-08-19T05:54:06","modified_gmt":"2024-08-19T05:54:06","slug":"ms-norroena-das-glueck-im-nordmeer","status":"publish","type":"magazin","link":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/","title":{"rendered":"MS Norr\u00f6na: F\u00e4hre zwischen den Welten"},"content":{"rendered":"\r\n<div class=\"cover--lead-in has-spacing--m\">\r\n\r\n    \r\n    <div class=\"cover--lead-in__content typo--tiempos\">\r\n\r\n        <div class=\"entry-categories\">\n\t<a class=\"post__tag\" href=\"https:\/\/visualjournalism.de\/magazin-kategorie\/wasser\/\" rel=\"category tag\">Wasser<\/a><\/div>\r\n        <h2 class=\"cover--lead-in__headline \">\r\n            F\u00e4hre zwischen den Welten        <\/h2>\r\n\r\n                    <div class=\"cover--lead-in__text\">\r\n                <p>Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route. <strong>Von\u00a0<a href=\"https:\/\/visualjournalism.de\/en\/stella-meyer-und-sarah-schneider\/\">Stella Meyer, Sarah Schneider <\/a>(Text) und <a href=\"https:\/\/visualjournalism.de\/en\/lisa-maria-gruber\/\">Lisa-Maria Gruber<\/a> (Fotos)<\/strong><\/p>\n            <\/div>\r\n        \r\n                    <div class=\"cover--lead-in__author\">\r\n                \r\n                    \r\n                            <figure class=\"cover--lead-in__author__image\">\r\n\r\n                                                                    <a href=\"https:\/\/visualjournalism.de\/stella-meyer-und-sarah-schneider\/\" target=\"_blank\">\r\n                                \r\n                                <img loading=\"lazy\" decoding=\"async\"\r\n                                    src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Stella-Meyer-L-und-Sarah-Schneider-R_-c-Fabian-Niebauer--68x68.jpg\"\r\n                                    srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Stella-Meyer-L-und-Sarah-Schneider-R_-c-Fabian-Niebauer--68x68.jpg 68w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Stella-Meyer-L-und-Sarah-Schneider-R_-c-Fabian-Niebauer--52x52.jpg 52w\"\r\n                                    width=\"68\"\r\n                                    height=\"68\"\r\n                                    alt=\"\"\r\n                                \/>\r\n\r\n                                                                    <\/a>\r\n                                \r\n                            <\/figure>\r\n\r\n                        \r\n                    \r\n                            <figure class=\"cover--lead-in__author__image\">\r\n\r\n                                                                    <a href=\"https:\/\/visualjournalism.de\/lisa-maria-gruber\/\" target=\"_blank\">\r\n                                \r\n                                <img loading=\"lazy\" decoding=\"async\"\r\n                                    src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/LMG_Portrait_9309-Bearbeitet-1-68x68.jpg\"\r\n                                    srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/LMG_Portrait_9309-Bearbeitet-1-68x68.jpg 68w, https:\/\/visualjournalism.de\/wp-content\/uploads\/LMG_Portrait_9309-Bearbeitet-1-52x52.jpg 52w, https:\/\/visualjournalism.de\/wp-content\/uploads\/LMG_Portrait_9309-Bearbeitet-1-96x96.jpg 96w\"\r\n                                    width=\"68\"\r\n                                    height=\"68\"\r\n                                    alt=\"\"\r\n                                \/>\r\n\r\n                                                                    <\/a>\r\n                                \r\n                            <\/figure>\r\n\r\n                                    <\/div><!-- .cover--lead-in__author -->\r\n        \r\n    <\/div><!-- .cover--lead-in__content -->\r\n\r\n    \r\n        <figure class=\"cover--lead-in__image cover--lead-in__media cover--lead-in__media--image\">\r\n            <img loading=\"lazy\" decoding=\"async\"\r\n                src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1920x1645.jpg\"\r\n                srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1920x1645.jpg 1920w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1024x878.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-2048x1755.jpg 2048w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1400x1200.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring_Reveries__92A9385-150x129.jpg 150w\"\r\n                width=\"1920\"\r\n                height=\"1645\"\r\n                alt=\"\"\r\n                style=\"object-position: 48.33% 56.42%\"\r\n            \/>\r\n        <\/figure>\r\n\r\n                    <span class=\"cover--lead-in__image-title\">\r\n                After around 24 hours, the ferry passes the Shet-land Islands \u2013 where the North Sea meets the North Atlantic. Copyright: Lisa-Maria Gruber. Use by arrangement only            <\/span>\r\n        \r\n    \r\n<\/div><!-- .cover--lead-in -->\r\n\r\n\n\n\n<p class=\"post__paragraph is-style-default has-spacing--default\"><strong>Die MS Norr\u00f6na verbindet seit 2003<\/strong> die abgelegenen F\u00e4r\u00f6er-Inseln und Island mit dem europ\u00e4ischen Festland. Von Hirtshals, einem malerischen Hafenort an der Nordspitze D\u00e4nemarks, \u00fcber die F\u00e4r\u00f6er-Inseln bis nach Sey\u00f0isfj\u00f6r\u00f0ur in Island transportiert sie unz\u00e4hlige Reisende und G\u00fcter. Die \u00dcberfahrt dauert etwa 48 Stunden und umfasst in der Regel zwei \u00dcbernachtungen an Bord. Mit einer Kapazit\u00e4t von bis zu 1.500 Passagieren ist die MS Norr\u00f6na eine der gr\u00f6\u00dften F\u00e4hren der Region.<\/p>\n\n\n\n<p class=\"post__paragraph has-spacing--default\">Die historische Bedeutung dieser Seeroute reicht bis in die Wikingerzeit zur\u00fcck, als die Nordm\u00e4nner mit ihren Knorr-Handelsschiffen den Atlantik \u00fcberquerten. Diese Tradition setzt der 57-j\u00e4hrige F\u00e4ringer Bogi Peterson fort, der seit 40 Jahren als Kapit\u00e4n durch die hohen Wellen navigiert. \u00abMein Vater war ein Seemann, mein Gro\u00dfvater war ein Seemann \u2013 es liegt mir im Blut\u00bb, erz\u00e4hlt er.<\/p>\n\n\n\n<p class=\"post__paragraph has-spacing--default\">Mit einer L\u00e4nge von knapp 170 Metern und breiten Bauweise ist die MS Norr\u00f6na ideal f\u00fcr die rauen Bedingungen des Nordatlantiks ausgestattet. Sie bietet Platz f\u00fcr 800 PKW und Kabinen f\u00fcr rund 1.500 Passagiere. Die F\u00e4hre transportiert wichtige G\u00fcter f\u00fcr die F\u00e4r\u00f6er-Inseln, insbesondere Holz, das dort aufgrund der kargen, felsigen Landschaft und salzigen Winde knapp ist. Im Gegenzug bringt sie frischen Fisch, vor allem Lachs, zur\u00fcck aufs Festland \u2013 ein bedeutender Teil des f\u00e4r\u00f6ischen Exports.<\/p>\n\n\n\n<p class=\"post__paragraph has-spacing--default\">Doch die MS Norr\u00f6na ist mehr als nur ein Transportmittel. Sie bietet eine Ruheoase in unserer hektischen Welt. \u00abAuf See gibt es nichts, was dich stresst\u00bb, sagt Chefingenieur Ey\u00f0un Djurhuus. \u00abAn Bord zu sein, ist alles, womit wir uns hier befassen m\u00fcssen.\u00bb Auch die 24-j\u00e4hrige Daniella Lykke findet Trost in ihrer Arbeit an Bord: \u00abImmer wenn ich aufs Oberdeck gehe und das offene Meer sehe, beruhigt mich das. Alle Probleme an Land verschwinden.\u00bb<\/p>\n\n\n\n<p class=\"post__paragraph has-spacing--m\">Mit gem\u00fctlichen Kabinen, Restaurants, einer Sauna und Unterhaltungsm\u00f6glichkeiten wie einem Playstationraum, Nachtclub und Casino bietet die MS Norr\u00f6na ihren Passagieren alles, um dem hektischen Alltag zu entfliehen und sich in der Weite des Ozeans treiben zu lassen.<\/p>\n\n\n\n<div class=\"devider has-spacing--none\">\n    <hr>\n<\/div>\n\n\n \n    \n    <div id=\"quote-block_d326de38131a552a21ab52d524508b6a\" class=\"block-quote has-spacing--m\">\n        <figure class=\"quote\">\n            <blockquote>\n                <p><strong>Auf See gibt es nichts, was dich stresst.<\/strong> Zuhause l\u00e4utet st\u00e4ndig das Telefon und verlangt deine Anwesenheit. An Bord zu sein, ist alles, womit wir uns hier befassen m\u00fcssen.<\/p>\n            <\/blockquote>\n\n            <figcaption>\n\n                            <img loading=\"lazy\" decoding=\"async\" class=\"portrait--inline\" src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Eydun_Djurhuus_cLisa-Maria-Gruber-_-52x52.jpg\" width=\"52\" height=\"52\" alt=\"\" \/>\n                            <span>Chefingenieur Ey\u00f0un Djurhuus<\/span>\n            <\/figcaption>\n            \n        <\/figure>\n    <\/div>\n\n\n\n \n\n<div class=\"photo-grid grid-layout--tableau has-spacing--m\">\n\n            \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-768x658.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-2-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"658\" \n                        alt=\"Eine M\u00f6we gleitet \u00fcber dem rauen Nordmeer. Fotografiert vom Deck der MS Norr\u00f6na. \"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>&#8222;Als Kind tr\u00e4umte ich davon, Navigator und Segler zu sein. Ich habe mit sechs oder sieben Jahren Segeln gelernt. Ich segelte mit meinem Opa in kleinen Booten. Ich bin nahe am Meer aufgewachsen, deshalb f\u00fchle ich eine starke Verbindung zum Meer.&#8220; &#8211; Bogi Peterson, Kapit\u00e4n der MS Norr\u00f6na<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-768x896.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-768x896.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-257x300.jpg 257w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-877x1024.jpg 877w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-1316x1536.jpg 1316w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-1400x1634.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-1050x1226.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-670x782.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-420x490.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-350x409.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-300x350.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1-150x175.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-3-1.jpg 1645w\" \n                        width=\"768\"  \n                        height=\"896\" \n                        alt=\"Daniella Lykke (links, 24) und Pauline Gibbas (rechts, 23) stehen nebeneinander auf dem Deck der MS Norr\u00f6na. Der Wind weht durch ihre Haare. Das nordische Klima ist sehr rau. Daniella ist D\u00e4nin und arbeitet seit zwei Jahren im Housekeeping, w\u00e4hrend Pauline aus Polen stammt und sich mit ihrer Arbeit an Bord ihr Musikstudium finanziert. \"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Daniella Lykke (l, 24) ist D\u00e4nin und arbeitet seit zwei Jahren im Housekeeping. Um ihren Kopf frei zu bekommen, geht sie ans Meer. Pauline Gibbas (r, 23) ist aus Polen und kam durch ihren Onkel an Bord. Mit ihrem Verdienst finanziert sie sich ihr Cello, denn sie studiert Musik.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-768x896.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-768x896.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-257x300.jpg 257w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-877x1024.jpg 877w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-1316x1536.jpg 1316w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-1400x1634.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-1050x1226.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-670x782.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-420x490.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-350x409.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-300x350.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1-150x175.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-11-1.jpg 1645w\" \n                        width=\"768\"  \n                        height=\"896\" \n                        alt=\"Eine Nahaufnahme von Martin V\u00e1goy, der K\u00fcchenchef der MS Norr\u00f6na. Er tr\u00e4gt eine schwarze Uniform und schaut mit einem nachdenklichen Blick zum Fenster hinaus, auf die Weiten der See.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Seit 2016 ist K\u00fcchenchef Martin V\u00e1goy Teil der Schiffsbesetzung. Fun Fact: Letztes Jahr hat er seinen Ein-Millionsten Pfannkuchen gebraten.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n            \n<\/div>\n\n    <figure class=\"block-photo post__image--full has-spacing--m no-title\">\n\n        <div class=\"post__image__container\">\n            <img loading=\"lazy\" decoding=\"async\" \n                src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-1400x1199.jpg\"\n                srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-4-1.jpg 1920w\"\n                width=\"1400\" \n                height=\"1199\"\n                alt=\"Ein Mann in Uniform sitzt in der Kontrollzentrale der MS Norr\u00f6na, umgeben von Bildschirmen und Schaltpulten. Er wirkt konzentriert, w\u00e4hrend er in der technischen Umgebung arbeitet, die mit Diagrammen und Notizen an der Wand hinter ihm ausgestattet ist.\" \n            \/>\n            \n                    <\/div><!-- post__image__container -->\n\n                    <figcaption class=\"post__image__caption--soehne\"><p>&#8222;Ich bin verantwortlich f\u00fcr alle Motoren an Bord und verwalte das Budget f\u00fcr die Maschine. Ich \u00fcberwache den Kauf aller Ersatzteile f\u00fcr den Maschinenraum und das alte Schiff. Ich leite dort unten ein Team von 24 Personen &#8211; 12 Personen an Bord und 12 zu Hause. Wir arbeiten in einer Vier-Wochen-Rotation: vier Wochen an Bord und dann vier Wochen zu Hause.&#8220; Ey\u00f0un Djurhuus ist 54 Jahre alt, urspr\u00fcnglich von den F\u00e4r\u00f6er-Inseln, und arbeitet als Chefingenieur an Bord der Norr\u00f6na.<\/p>\n<\/figcaption>\n        \n    <\/figure><!-- post__image -->\n\n\n\n\n<div class=\"devider has-spacing--none\">\n    <hr>\n<\/div>\n\n\n \n    \n    <div id=\"quote-block_09b19552066f4500785af0c9fd061281\" class=\"block-quote has-spacing--m\">\n        <figure class=\"quote\">\n            <blockquote>\n                <p><strong>Mein Vater ist Seemann,<\/strong> daher bin ich auf See aufgewachsen und f\u00fchle eine tiefe emotionale Verbundenheit damit. W\u00e4hrend einige das Leben auf einem Boot als blo\u00dfen Job betrachten, empfinde ich eine Erf\u00fcllung darin.<\/p>\n            <\/blockquote>\n\n            <figcaption>\n\n                            <img loading=\"lazy\" decoding=\"async\" class=\"portrait--inline\" src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Lovisa-Duvander_cLisa-Maria-Gruber-_-52x52.jpg\" width=\"52\" height=\"52\" alt=\"\" \/>\n                            <span>Lovisa Duvander, Oberkellnerin<\/span>\n            <\/figcaption>\n            \n        <\/figure>\n    <\/div>\n\n\n\n \n\n<div class=\"photo-grid grid-layout--tableau has-spacing--m\">\n\n            \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-768x768.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-768x768.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-300x300.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-1024x1024.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-150x150.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-1536x1536.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-1400x1400.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-1050x1050.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-670x670.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-420x420.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-350x350.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-52x52.jpg 52w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-68x68.jpg 68w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1-96x96.jpg 96w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-6-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"768\" \n                        alt=\"Helmut Zimmermann sitzt in einem der vielen R\u00e4ume der MS Norr\u00f6na. Er tr\u00e4gt eine runde schwarze Brille, hat einen wei\u00dfen Bart und eine Glatze. Mit seiner Hand st\u00fctzt er seinen Kopf, w\u00e4hrend er in Erinnerungen schwelgt.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Helmut Zimmermann erinnert sich gerne an seine Erfahrungen als Seemann zur\u00fcck. Ein Kapitel seines Lebens, das von einer tiefen Wertsch\u00e4tzung f\u00fcr die Weite des Meeres gepr\u00e4gt war. Auch heute noch findet er Gl\u00fcck in der Weite des Ozeans.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-768x658.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-5-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"658\" \n                        alt=\"Im Maschinenraum der MS Norr\u00f6na steht eine Spielzeugfigur von Arielle die Meerjungfrau. \"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Die Besatzung bem\u00fcht sich, eine positive Stimmung und Atmosph\u00e4re an Bord aufrechtzuerhalten. Dies ist wichtig, da viele von ihnen weit weg von zu Hause sind.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-768x658.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"658\" \n                        alt=\"Ein Besatzungsmitglied steht im Innenraum der MS Norr\u00f6na, wo mehrere leere Tische und St\u00fchle vor gro\u00dfen Fenstern stehen. Das sanfte Licht des fr\u00fchen Abe\nnds schafft eine tr\u00e4umerische Atmosph\u00e4re.\"  \n                    \/>\n\n                    \n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n            \n<\/div>\n\n    <figure class=\"block-photo post__image--full has-spacing--m no-title\">\n\n        <div class=\"post__image__container\">\n            <img loading=\"lazy\" decoding=\"async\" \n                src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-1400x1199.jpg\"\n                srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-14-1.jpg 1920w\"\n                width=\"1400\" \n                height=\"1199\"\n                alt=\"Der Kapit\u00e4n der MS Norr\u00f6na \" \n            \/>\n            \n                    <\/div><!-- post__image__container -->\n\n                    <figcaption class=\"post__image__caption--soehne\"><p>Bogi Peterson ist 57 Jahre alt, stammt urspr\u00fcnglich von den F\u00e4r\u00f6er-Inseln und ist der Kapit\u00e4n an Bord der Norr\u00f6na.<\/p>\n<\/figcaption>\n        \n    <\/figure><!-- post__image -->\n\n\n\n\n<div class=\"devider has-spacing--none\">\n    <hr>\n<\/div>\n\n\n \n    \n    <div id=\"quote-block_86f7aba326e4781a366261d93638650a\" class=\"block-quote has-spacing--m\">\n        <figure class=\"quote\">\n            <blockquote>\n                <p><strong>Wenn ich auf dem Schiff bin<\/strong> und auf den Ozean schaue, ist es so, als w\u00fcrde ich meinen Geist sp\u00fcren.<\/p>\n            <\/blockquote>\n\n            <figcaption>\n\n                            <img loading=\"lazy\" decoding=\"async\" class=\"portrait--inline\" src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Daniella-Lyke_cLisa-Maria-Gruber-_-3-52x52.jpg\" width=\"52\" height=\"52\" alt=\"\" \/>\n                            <span>Daniella Lykke<\/span>\n            <\/figcaption>\n            \n        <\/figure>\n    <\/div>\n\n\n\n \n\n<div class=\"photo-grid grid-layout--tableau has-spacing--m\">\n\n            \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-768x576.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-768x576.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-300x225.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-1024x768.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-1536x1152.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-1400x1050.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-1050x788.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-670x503.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-420x315.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-350x263.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1-150x113.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-15-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"576\" \n                        alt=\"Eine Kabine der MS Norr\u00f6na ist mit einem Bett ausgestattet. Man hat durch ein kleines Fenster den Blick aufs Meer. Ein wenig Licht scheint durch den Raum und sorgt f\u00fcr eine gem\u00fctliche Atmosph\u00e4re.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Auf Deutsch \u00fcbersetzt sich &#8218;Nordmeer&#8216; ins F\u00e4r\u00f6ische als &#8218;Norr\u00f6na&#8216;. Die Reise nach Island von M\u00e4rz bis Mai und von Mitte August bis November dauert etwas \u00fcber drei Tage.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-768x658.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-7-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"658\" \n                        alt=\"Eine Gruppe von Reisenden befindet sich im Aufenthaltsraum der MS Norr\u00f6na. Gemeinsam sitzen sie an einem Tisch und spielen ein W\u00fcrfelspiel. Im Hintergrund sieht man weihnachtliche Dekoration und eine gro\u00dfe Fensterfront.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>W\u00e4hrend der Reise von T\u00f3rshavn nach Hirtshals spielen Reisende ein W\u00fcrfelspiel.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-768x658.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-1024x877.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-1536x1316.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-1400x1199.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-16-1.jpg 1920w\" \n                        width=\"768\"  \n                        height=\"658\" \n                        alt=\"Die MS Norr\u00f6na passiert die raue Landschaft der F\u00e4r\u00f6er Inseln. In der Ferne regnet es. Inmitten des Nordatlantiks befinden sich die Inseln mit satten gr\u00fcnen Wiesen und Wasserf\u00e4llen.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>Die raue Landschaft zeichnet sich durch \u00fcppige gr\u00fcne Wiesen, steile Wasserf\u00e4lle und hohe Klippen aus. Die abgelegene Lage, die von Wolken verh\u00fcllten Berge und das wechselhafte Wetter verleihen diesem Ort eine mystische Atmosph\u00e4re. Hier kann man alle vier Jahreszeiten an einem einzigen Tag erleben.<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n            \n<\/div>\n\n \n\n<div class=\"photo-grid grid-layout--2col-5 has-spacing--m\">\n\n            \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-768x896.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-768x896.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-257x300.jpg 257w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-877x1024.jpg 877w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-1316x1536.jpg 1316w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-1400x1634.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-1050x1226.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-670x782.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-420x490.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-350x409.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-300x350.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1-150x175.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-17-1.jpg 1645w\" \n                        width=\"768\"  \n                        height=\"896\" \n                        alt=\"Rakul Mikkelsen schaut vertr\u00e4umt zur linken Seite. Sie steht in ihrer Uniform auf der MS Norr\u00f6na, denn sie arbeitet als Kellnerin an Bord. \"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>&#8222;Wenn ich auf dem Wasser bin, versp\u00fcre ich ein tiefes Gef\u00fchl der Ruhe. Es ist, als ob ich mich von der Welt abkoppeln und einfach Mitten im Nirgendwo existieren k\u00f6nnte. Ich genie\u00dfe das Leben mit meinen Kolleg:innen.&#8220; &#8211; Rakul<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n                    \n                \n\n            <div class=\"photo-grid__image\">\n\n                <figure>\n\n                    <img loading=\"lazy\" decoding=\"async\"  \n                        src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-768x896.jpg\" \n                        srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-768x896.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-257x300.jpg 257w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-877x1024.jpg 877w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-1316x1536.jpg 1316w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-1400x1634.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-1050x1226.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-670x782.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-420x490.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-350x409.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-300x350.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1-150x175.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-8-1.jpg 1645w\" \n                        width=\"768\"  \n                        height=\"896\" \n                        alt=\"Unter anderem befindet sich ein Spielautomat und ein Hocker im Casino der MS Norr\u00f6na. Rechts daneben gibt es ein Fenster, welches f\u00fcr Tageslicht im Rauminneren sorgt. Man sieht die Wellen des Nordatlantiks.\"  \n                    \/>\n\n                    \n                                            <figcaption class=\"photo-grid__image__caption--soehne\"><p>D<\/p>\n<\/figcaption>\n                    \n                <\/figure>\n\n            <\/div><!-- photo-grid__image -->    \n\n\n            \n\n            \n<\/div>\n\n    <figure class=\"block-photo post__image--full has-spacing--m no-title\">\n\n        <div class=\"post__image__container\">\n            <img loading=\"lazy\" decoding=\"async\" \n                src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-1400x1200.jpg\"\n                srcset=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-1400x1200.jpg 1400w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-300x257.jpg 300w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-1024x878.jpg 1024w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-768x658.jpg 768w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-1536x1317.jpg 1536w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-1050x900.jpg 1050w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-670x574.jpg 670w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-420x360.jpg 420w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-350x300.jpg 350w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1-150x129.jpg 150w, https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber-18-1.jpg 1920w\"\n                width=\"1400\" \n                height=\"1200\"\n                alt=\"Das Innere der MS Norr\u00f6na wird in warmes Licht der Abendsonne getaucht. St\u00fchle und Tische im 50er Jahre Look sind im Raum platziert. Im Hintergrund sieht man den Nordatlantik durch die Fensterfront.\" \n            \/>\n            \n                    <\/div><!-- post__image__container -->\n\n                    <figcaption class=\"post__image__caption--soehne\"><p>Die Nordsee wird von Sonnenlicht durchflutet, ihre Oberfl\u00e4che ist ruhig und der Wind fl\u00fcstert kaum. Die MS Norr\u00f6na ist nicht nur ein Schiff, sondern ein Symbol der Verbindung und ein Bewahrer einer Geschichte, die so alt ist wie die See selbst.<\/p>\n<\/figcaption>\n        \n    <\/figure><!-- post__image -->\n\n\n\n\n<div class=\"devider has-spacing--none\">\n    <hr>\n<\/div>\n\n\n \n    \n    <div id=\"quote-block_8920a93c0ae80b57abfc329939225b64\" class=\"block-quote has-spacing--m\">\n        <figure class=\"quote\">\n            <blockquote>\n                <p><strong>Mein Vater<\/strong> war ein Seemann, mein Gro\u00dfvater war ein Seemann und so weiter. Als Kind habe ich deshalb oft davon getr\u00e4umt, selbst Kapit\u00e4n zu sein und zu segeln. Es liegt mir also fast im Blut oder in meiner DNA<\/p>\n            <\/blockquote>\n\n            <figcaption>\n\n                            <img loading=\"lazy\" decoding=\"async\" class=\"portrait--inline\" src=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Portrait_Bogi-Peterson_cLisa-Maria-Gruber-_-52x52.jpg\" width=\"52\" height=\"52\" alt=\"\" \/>\n                            <span>Kapit\u00e4n Bogi Peterson<\/span>\n            <\/figcaption>\n            \n        <\/figure>\n    <\/div>\n\n\n\n","protected":false},"author":70,"featured_media":41956,"template":"","tags":[],"magazinkategorie":[185],"class_list":["post-40823","magazin","type-magazin","status-publish","has-post-thumbnail","hentry","magazinkategorie-wasser"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F\u00e4hre zwischen den Welten<\/title>\n<meta name=\"description\" content=\"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MS Norr\u00f6na: F\u00e4hre zwischen den Welten\" \/>\n<meta property=\"og:description\" content=\"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/\" \/>\n<meta property=\"og:site_name\" content=\"Visual Journalism and Documentary Photography\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-19T05:54:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HsHannover\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/\",\"name\":\"F\u00e4hre zwischen den Welten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg\",\"datePublished\":\"2024-07-19T11:51:54+00:00\",\"dateModified\":\"2024-08-19T05:54:06+00:00\",\"description\":\"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg\",\"contentUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg\",\"width\":1920,\"height\":1645,\"caption\":\"Ein Besatzungsmitglied steht im Innenraum der MS Norr\u00f6na, wo mehrere leere Tische und St\u00fchle vor gro\u00dfen Fenstern stehen. Das sanfte Licht des fr\u00fchen Abends schafft eine tr\u00e4umerische Atmosph\u00e4re.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/wasser\\\/ms-norroena-das-glueck-im-nordmeer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazin\",\"item\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MS Norr\u00f6na: F\u00e4hre zwischen den Welten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\",\"name\":\"Visual Journalism and Documentary Photography\",\"description\":\"All about the bilingual bachelor&#039;s program at Hannover University of Applied Sciences and Arts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#organization\"},\"alternateName\":\"visualjournalism.de\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#organization\",\"name\":\"Hochschule Hannover \u2013 University of Applied Sciences and Arts\",\"alternateName\":\"HsH\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/logo-hochschule-hannover.png\",\"contentUrl\":\"https:\\\/\\\/visualjournalism.de\\\/wp-content\\\/uploads\\\/logo-hochschule-hannover.png\",\"width\":363,\"height\":270,\"caption\":\"Hochschule Hannover \u2013 University of Applied Sciences and Arts\"},\"image\":{\"@id\":\"https:\\\/\\\/visualjournalism.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/wwwfotostudentende\\\/100065173703897\\\/\",\"https:\\\/\\\/x.com\\\/HsHannover\",\"https:\\\/\\\/www.instagram.com\\\/visualjournalism.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F\u00e4hre zwischen den Welten","description":"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/","og_locale":"en_US","og_type":"article","og_title":"MS Norr\u00f6na: F\u00e4hre zwischen den Welten","og_description":"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.","og_url":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/","og_site_name":"Visual Journalism and Documentary Photography","article_publisher":"https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/","article_modified_time":"2024-08-19T05:54:06+00:00","og_image":[{"width":1920,"height":1645,"url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@HsHannover","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/","url":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/","name":"F\u00e4hre zwischen den Welten","isPartOf":{"@id":"https:\/\/visualjournalism.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/#primaryimage"},"image":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/#primaryimage"},"thumbnailUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg","datePublished":"2024-07-19T11:51:54+00:00","dateModified":"2024-08-19T05:54:06+00:00","description":"Von D\u00e4nemark \u00fcber die F\u00e4r\u00f6er-Inseln nach Island \u2013 eine Fahrt durch die raue Sch\u00f6nheit des Nordatlantiks auf einer historischen Route.","breadcrumb":{"@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/#primaryimage","url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg","contentUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/Seafaring-Reveries_Lisa-Maria-Gruber.jpg","width":1920,"height":1645,"caption":"Ein Besatzungsmitglied steht im Innenraum der MS Norr\u00f6na, wo mehrere leere Tische und St\u00fchle vor gro\u00dfen Fenstern stehen. Das sanfte Licht des fr\u00fchen Abends schafft eine tr\u00e4umerische Atmosph\u00e4re."},{"@type":"BreadcrumbList","@id":"https:\/\/visualjournalism.de\/en\/magazine\/wasser\/ms-norroena-das-glueck-im-nordmeer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visualjournalism.de\/en\/"},{"@type":"ListItem","position":2,"name":"Magazin","item":"https:\/\/visualjournalism.de\/en\/magazine\/"},{"@type":"ListItem","position":3,"name":"MS Norr\u00f6na: F\u00e4hre zwischen den Welten"}]},{"@type":"WebSite","@id":"https:\/\/visualjournalism.de\/en\/#website","url":"https:\/\/visualjournalism.de\/en\/","name":"Visual Journalism and Documentary Photography","description":"All about the bilingual bachelor&#039;s program at Hannover University of Applied Sciences and Arts.","publisher":{"@id":"https:\/\/visualjournalism.de\/en\/#organization"},"alternateName":"visualjournalism.de","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visualjournalism.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visualjournalism.de\/en\/#organization","name":"Hochschule Hannover \u2013 University of Applied Sciences and Arts","alternateName":"HsH","url":"https:\/\/visualjournalism.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visualjournalism.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visualjournalism.de\/wp-content\/uploads\/logo-hochschule-hannover.png","contentUrl":"https:\/\/visualjournalism.de\/wp-content\/uploads\/logo-hochschule-hannover.png","width":363,"height":270,"caption":"Hochschule Hannover \u2013 University of Applied Sciences and Arts"},"image":{"@id":"https:\/\/visualjournalism.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/wwwfotostudentende\/100065173703897\/","https:\/\/x.com\/HsHannover","https:\/\/www.instagram.com\/visualjournalism.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin\/40823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin"}],"about":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/types\/magazin"}],"author":[{"embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/users\/70"}],"version-history":[{"count":0,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazin\/40823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/media\/41956"}],"wp:attachment":[{"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/media?parent=40823"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/tags?post=40823"},{"taxonomy":"magazinkategorie","embeddable":true,"href":"https:\/\/visualjournalism.de\/en\/wp-json\/wp\/v2\/magazinkategorie?post=40823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}